{"id":8166,"date":"2022-09-21T13:29:01","date_gmt":"2022-09-21T13:29:01","guid":{"rendered":"https:\/\/henpartynight.com\/?page_id=8166"},"modified":"2024-04-16T09:13:51","modified_gmt":"2024-04-16T09:13:51","slug":"ibiza","status":"publish","type":"page","link":"https:\/\/henpartynight.com\/it\/bar-crawl-2\/ibiza\/","title":{"rendered":"Ibiza"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div data-q_id=\"#app\"    class=\"vc_row wpb_row section vc_row-fluid  vc_custom_1455181468772 grid_section\" style=' text-align:center;'><div class=\"section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-10 vc_col-lg-offset-3 vc_col-lg-6 vc_col-md-offset-3 vc_col-md-6 vc_col-sm-offset-1\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>Bar Crawl Ibiza<\/h2>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  small center\" style=\"\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3>I Bar Crawl Ibiza sono diventati un pilastro importante della scena delle feste. Fate un tour di 3-5 bar con una guida locale. In ogni bar avrete uno shot incluso e in alcuni pacchetti avrete anche l'opzione di un open bar per 1 ora. Alla fine del Pub Crawl, avrete l'ingresso gratuito nei migliori club della citt\u00e0.<\/h3>\n\n\t\t<\/div>\n\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid  vc_custom_1455201911382 grid_section\" style='background-color:#f5f5f5; text-align:center;'><div class=\"section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>Guardate come Bar Crawl soddisfa i vostri desideri e le vostre esigenze, contate su di noi.<\/h2>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  small center\" style=\"\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3>Specialisti in Bar Crawl Ibiza! Rendiamo il vostro Pub Crawl unico e originale! Incontrate persone da tutto il mondo in questa attivit\u00e0 dinamica e divertente!<\/h3>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  transparent\" style=\"margin-top: 35px;margin-bottom: 0px;height: 0px;\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"dm-title\">\n<h2>Bar Crawl Ibiza - Esplorate l'isola con una guida locale!<\/h2>\n<\/div>\n<p>Se siete alla ricerca di una serata folle o volete semplicemente conoscere nuove persone, siete nel posto giusto! <a href=\"https:\/\/henpartynight.com\/it\/\">Henpartynight's<\/a> Bar Crawl Ibiza \u00e8 la scelta migliore. Potrete conoscere la notte in un ambiente sicuro e divertente con una guida locale e altri gruppi che condivideranno l'attivit\u00e0 con voi.<br \/>\nIn giro per i pub <a href=\"https:\/\/es.wikipedia.org\/wiki\/Ibiza\">Ibiza<\/a> non solo visiterete i pub e i bar tradizionali di ogni citt\u00e0, ma anche i migliori locali notturni alla moda. La guida locale parla diverse lingue per rendere la vostra attivit\u00e0 pi\u00f9 facile e dinamica.<\/p>\n<p>Conoscete la magica atmosfera della vita notturna dell'isola bianca di Ibiza con una guida locale e altri gruppi. Per cominciare, conoscerete la zona dei bar sulla spiaggia di Sant Antonio, la citt\u00e0 vecchia di Ibiza e finirete per visitare le migliori discoteche. Ibiza \u00e8 un punto di riferimento mondiale per la sua famosa vita notturna e per le feste di qualit\u00e0 con i migliori DJ, animatori, luci, suoni e musica. Non potete perdere questa opportunit\u00e0!<\/p>\n<div class=\"row-fluid\">\n<p><strong>La festa Ibiza Pub Crawl include<\/strong>:<\/p>\n<ul>\n<li>Guida locale durante il tour<\/li>\n<li>Free Shots - Uno in ogni bar<\/li>\n<li>Ingresso gratuito nei bar, pub e discoteche di vostra scelta fino alle 6 del mattino.<\/li>\n<li>Sconti sulle bevande. Sia sulle bevande che sulla birra per tutta la notte.<\/li>\n<\/ul>\n<p><strong>Giorni e orari:<\/strong><\/p>\n<ul>\n<li>Ogni giorno<\/li>\n<li>Il nostro Pub Crawl si \u00e8 svolto dalle 22.00 alle 24.00 e si \u00e8 concluso alle 6.00 in discoteca.<\/li>\n<\/ul>\n<p>Per il nostro bar crawl vestire casual. Per l'ingresso al club vestirsi in modo elegante\/casual. La politica del club prevede il divieto di indossare pantaloncini da spiaggia o da bagno, infradito o canottiere.<\/p>\n<h4>Preparatevi a divertirvi in modo scandaloso a bordo dell'Original Bar Crawl!<\/h4>\n<p>Un'atmosfera incredibile e una festa pazzesca! Non c'\u00e8 dubbio che dovete provare questa esperienza con i vostri amici!<\/p>\n<h4>Contate su di noi per rendere tutto perfetto per voi. Contattateci e vi renderemo tutto pi\u00f9 semplice!<\/h4>\n<p>I Pub Crawl sono diventati un pilastro importante per gli addii al nubilato e al celibato. Negli ultimi anni, il mercato dei bar crawl \u00e8 cresciuto notevolmente e ogni marchio presenta il proprio concetto, il proprio genere musicale e il proprio percorso.<\/p>\n<p>Henpartynight ha scelto con cura le migliori compagnie di tour Pub Crawl.<\/p>\n<p>Scegliete questo Bar Crawl, godetevi la magica notte di ballo. Anche con la bella gente che vi circonda.<\/p>\n<p>Inserite questa festa Ibiza Pub Crawl nei vostri programmi. Non potete perdervi questa festa!<\/p>\n<\/div>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  transparent\" style=\"margin-top: 39px;margin-bottom: 0px;height: 0px;\"><\/div><a  itemprop=\"url\" href=\"https:\/\/henpartynight.com\/it\/contatto-addio-al-nubilato\/\" target=\"_self\"  class=\"qbutton  medium white default\" style=\"\">Chiedete il vostro budget senza impegno<\/a><div class=\"separator  transparent\" style=\"margin-top: 53px;margin-bottom: 0px;height: 0px;\"><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"separator  transparent\" style=\"margin-top: 4px;margin-bottom: 0px;height: 0px;\"><\/div>\n\t<div class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/henpartynight.com\/wp-content\/uploads\/2022\/09\/pexels-edoardo-tommasini-3249760-scaled.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"Le migliori discoteche di Ibiza\" title=\"Bar Crawl\" srcset=\"https:\/\/henpartynight.com\/wp-content\/uploads\/2022\/09\/pexels-edoardo-tommasini-3249760-scaled.jpg 2560w, https:\/\/henpartynight.com\/wp-content\/uploads\/2022\/09\/pexels-edoardo-tommasini-3249760-300x200.jpg 300w, https:\/\/henpartynight.com\/wp-content\/uploads\/2022\/09\/pexels-edoardo-tommasini-3249760-1024x683.jpg 1024w, https:\/\/henpartynight.com\/wp-content\/uploads\/2022\/09\/pexels-edoardo-tommasini-3249760-768x512.jpg 768w, https:\/\/henpartynight.com\/wp-content\/uploads\/2022\/09\/pexels-edoardo-tommasini-3249760-1536x1024.jpg 1536w, https:\/\/henpartynight.com\/wp-content\/uploads\/2022\/09\/pexels-edoardo-tommasini-3249760-2048x1365.jpg 2048w, https:\/\/henpartynight.com\/wp-content\/uploads\/2022\/09\/pexels-edoardo-tommasini-3249760-700x467.jpg 700w, https:\/\/henpartynight.com\/wp-content\/uploads\/2022\/09\/pexels-edoardo-tommasini-3249760-600x400.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/henpartynight.com\/wp-content\/uploads\/2017\/06\/HenPartyNight-150x150.png\" class=\"vc_single_image-img attachment-thumbnail lazyload\" alt=\"\" title=\"Serata di addio al nubilato\" data-srcset=\"https:\/\/henpartynight.com\/wp-content\/uploads\/2017\/06\/HenPartyNight-150x150.png 150w, https:\/\/henpartynight.com\/wp-content\/uploads\/2017\/06\/HenPartyNight-300x300.png 300w, https:\/\/henpartynight.com\/wp-content\/uploads\/2017\/06\/HenPartyNight-100x100.png 100w, https:\/\/henpartynight.com\/wp-content\/uploads\/2017\/06\/HenPartyNight-570x570.png 570w, https:\/\/henpartynight.com\/wp-content\/uploads\/2017\/06\/HenPartyNight-500x500.png 500w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f8800-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"8800\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/pages\/8166#wpcf7-f8800-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/it\/wp-json\/wp\/v2\/pages\/8166#wpcf7-f8800-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"8800\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f8800-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<label> Nome (obbligatorio)\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n\n<label> Il vostro indirizzo e-mail (obbligatorio)\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n\n<label> Il vostro telefono + codice paese (obbligatorio)\n<span class=\"wpcf7-form-control-wrap\" data-name=\"telefono\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Esempio-+336xxxxx\" value=\"\" type=\"tel\" name=\"telefono\" \/><\/span> <\/label>\n\n<label> SERVIZIO DI DESTINAZIONE (obbligatorio)\n   <span class=\"wpcf7-form-control-wrap\" data-name=\"City\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"City\"><option value=\"Barcelona\">Barcellona<\/option><option value=\"Madrid\">Madrid<\/option><option value=\"Ibiza\">Ibiza<\/option><option value=\"Mallorca\">Maiorca<\/option><option value=\"Marbella\">Marbella<\/option><option value=\"Valencia\">Valencia<\/option><option value=\"Sitges\">Sitges<\/option><option value=\"Lloret de Mar\">Lloret de Mar<\/option><option value=\"Benidorm\">Benidorm<\/option><option value=\"Oporto\">Porto<\/option><option value=\"Albuferia\">Albuferia<\/option><option value=\"Lisbon\">Lisbona<\/option><option value=\"Warsaw\">Varsavia<\/option><\/select><\/span> <\/label>\n\n<label> Servizio\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"Service\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"Service\"><option value=\"Cheeky Butler\">Maggiordomo sfacciato<\/option><option value=\"Cocktail Class\">Classe Cocktail<\/option><option value=\"Stripper\">Spogliarellista<\/option><option value=\"Boat Party\">Festa in barca<\/option><option value=\"Dwarf\">Nano<\/option><option value=\"Limousines\">Limousine<\/option><option value=\"Life Drawing\">Disegno dal vero<\/option><option value=\"Bar Crawl\">Bar Crawl<\/option><option value=\"Mud Wrestling\">Lotta nel fango<\/option><option value=\"Wedding Planning\">Pianificazione del matrimonio<\/option><\/select><\/span> <\/label>\n\n<label> Number of people (required)\n<span class=\"wpcf7-form-control-wrap\" data-name=\"People\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"People\"><option value=\"1\">1<\/option><option value=\"2\">2<\/option><option value=\"3\">3<\/option><option value=\"4\">4<\/option><option value=\"5\">5<\/option><option value=\"6\">6<\/option><option value=\"7\">7<\/option><option value=\"8\">8<\/option><option value=\"9\">9<\/option><option value=\"10\">10<\/option><option value=\"11\">11<\/option><option value=\"12\">12<\/option><option value=\"13\">13<\/option><option value=\"14\">14<\/option><option value=\"15\">15<\/option><option value=\"16\">16<\/option><option value=\"17\">17<\/option><option value=\"18\">18<\/option><option value=\"19\">19<\/option><option value=\"20\">20<\/option><option value=\"21\">21<\/option><option value=\"22\">22<\/option><option value=\"23\">23<\/option><option value=\"24\">24<\/option><option value=\"25\">25<\/option><option value=\"26\">26<\/option><option value=\"27\">27<\/option><option value=\"28\">28<\/option><option value=\"29\">29<\/option><option value=\"30\">30<\/option><option value=\"M\u00e1s de 30\">M\u00e1s de 30<\/option><\/select><\/span> <\/label>\n\n<label> Event date (required)\n<span class=\"wpcf7-form-control-wrap\" data-name=\"date\"><input class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-required wpcf7-validates-as-date\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"date\" name=\"date\" \/><\/span> <\/label>\n\n<label> Messaggio\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n\nInput this code: <input type=\"hidden\" name=\"_wpcf7_captcha_challenge_captcha-170\" value=\"1456515598\" \/><img decoding=\"async\" class=\"wpcf7-form-control wpcf7-captchac wpcf7-captcha-captcha-170 lazyload\" width=\"72\" height=\"24\" alt=\"captcha\" data-src=\"https:\/\/henpartynight.com\/wp-content\/uploads\/wpcf7_captcha\/1456515598.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 72px; --smush-placeholder-aspect-ratio: 72\/24;\" \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"captcha-170\"><input size=\"4\" maxlength=\"4\" class=\"wpcf7-form-control wpcf7-captchar\" autocomplete=\"off\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"captcha-170\" \/><\/span>\n\n<br><span><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-279\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"acceptance-279\" value=\"1\" aria-invalid=\"false\" \/><\/span><\/span><\/span> Ho letto e accetto il <a target=\"_blank\" rel=\"nofollow noopener noreferrer\" href=\"https:\/\/henpartynight.com\/it\/avisos-legales\/\">Consulente legale<\/a> y la <a target=\"_blank\" rel=\"nofollow noopener noreferrer\" href=\"https:\/\/henpartynight.com\/it\/politica-de-privacidad\/\">Informativa sulla privacy<\/a>.<\/span><br><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Inviare\" \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"it\"\/><\/form>\n<\/div>\n\n\n\t\t<\/div>\n\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid  vc_custom_1455027288649 grid_section\" style=' text-align:left;'><div class=\"section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img lazyload\" data-src=\"https:\/\/henpartynight.com\/wp-content\/uploads\/2016\/02\/henparty-250x200.jpg\" width=\"250\" height=\"200\" alt=\"despedidas de soltera\" title=\"henparty\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 250px; --smush-placeholder-aspect-ratio: 250\/200;\" \/><\/div>\n\t\t<\/div>\n\t<\/div>\n<div class=\"separator  transparent\" style=\"margin-top: 40px;margin-bottom: 0px;height: 0px;\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>Addio al nubilato<\/h4>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  transparent\" style=\"margin-top: 23px;margin-bottom: 0px;height: 0px;\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Vi offriamo la pi\u00f9 ampia variet\u00e0 di addii al nubilato originali in tutte le destinazioni (e ci espandiamo continuamente), non solo in Spagna ma anche nei luoghi pi\u00f9 caldi d'Europa e d'America.<\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  transparent\" style=\"margin-top: 28px;margin-bottom: 0px;height: 0px;\"><\/div><div class='q_list circle'><\/p>\n<ul>\n<li>Madrid<\/li>\n<li>Barcellona<\/li>\n<li>Valencia<\/li>\n<li>Maiorca<\/li>\n<li>Ibiza<\/li>\n<li>M\u00e1s<\/li>\n<\/ul>\n<p><\/div><div class=\"separator  transparent\" style=\"margin-top: 40px;margin-bottom: 0px;height: 0px;\"><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img lazyload\" data-src=\"https:\/\/henpartynight.com\/wp-content\/uploads\/2016\/02\/stagnight-250x200.jpg\" width=\"250\" height=\"200\" alt=\"despedidas de soltero\" title=\"addio al celibato\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 250px; --smush-placeholder-aspect-ratio: 250\/200;\" \/><\/div>\n\t\t<\/div>\n\t<\/div>\n<div class=\"separator  transparent\" style=\"margin-top: 40px;margin-bottom: 0px;height: 0px;\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>Addio al celibato<\/h4>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  transparent\" style=\"margin-top: 23px;margin-bottom: 0px;height: 0px;\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Vi offriamo la pi\u00f9 ampia variet\u00e0 di feste di addio al celibato originali in tutte le destinazioni (e ci espandiamo continuamente), non solo in Spagna ma anche nei luoghi pi\u00f9 caldi d'Europa e d'America.<\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  transparent\" style=\"margin-top: 28px;margin-bottom: 0px;height: 0px;\"><\/div><div class='q_list circle'><\/p>\n<ul>\n<li>Madrid<\/li>\n<li>Barcellona<\/li>\n<li>Valencia<\/li>\n<li>Maiorca<\/li>\n<li>Ibiza<\/li>\n<li>M\u00e1s<\/li>\n<\/ul>\n<p><\/div><div class=\"separator  transparent\" style=\"margin-top: 40px;margin-bottom: 0px;height: 0px;\"><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img lazyload\" data-src=\"https:\/\/henpartynight.com\/wp-content\/uploads\/2016\/02\/bodas-250x200.jpg\" width=\"250\" height=\"200\" alt=\"bodas\" title=\"bodas\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 250px; --smush-placeholder-aspect-ratio: 250\/200;\" \/><\/div>\n\t\t<\/div>\n\t<\/div>\n<div class=\"separator  transparent\" style=\"margin-top: 40px;margin-bottom: 0px;height: 0px;\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>Matrimonio<\/h4>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  transparent\" style=\"margin-top: 23px;margin-bottom: 0px;height: 0px;\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Vi offriamo la pi\u00f9 ampia variet\u00e0 di organizzazione di matrimoni originali in tutte le destinazioni (e che espandiamo continuamente), non solo in Spagna ma anche nei punti pi\u00f9 caldi d'Europa e d'America.<\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  transparent\" style=\"margin-top: 28px;margin-bottom: 0px;height: 0px;\"><\/div><div class='q_list circle'><\/p>\n<ul>\n<li>Madrid<\/li>\n<li>Barcellona<\/li>\n<li>Valencia<\/li>\n<li>Maiorca<\/li>\n<li>Ibiza<\/li>\n<li>M\u00e1s<\/li>\n<\/ul>\n<p><\/div><div class=\"separator  transparent\" style=\"margin-top: 40px;margin-bottom: 0px;height: 0px;\"><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img lazyload\" data-src=\"https:\/\/henpartynight.com\/wp-content\/uploads\/2016\/02\/fiestasprivadas-250x200.jpg\" width=\"250\" height=\"200\" alt=\"Feste\" title=\"feste private\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 250px; --smush-placeholder-aspect-ratio: 250\/200;\" \/><\/div>\n\t\t<\/div>\n\t<\/div>\n<div class=\"separator  transparent\" style=\"margin-top: 40px;margin-bottom: 0px;height: 0px;\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>Feste private - Eventi<\/h4>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  transparent\" style=\"margin-top: 23px;margin-bottom: 0px;height: 0px;\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Vi offriamo la pi\u00f9 ampia variet\u00e0 di feste private o tutti i tipi di eventi originali e unici in tutte le destinazioni (e in continua espansione), non solo in Spagna ma anche nei luoghi pi\u00f9 caldi d'Europa e d'America.<\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  transparent\" style=\"margin-top: 28px;margin-bottom: 0px;height: 0px;\"><\/div><div class='q_list circle'><\/p>\n<ul>\n<li>Madrid<\/li>\n<li>Barcellona<\/li>\n<li>Valencia<\/li>\n<li>Maiorca<\/li>\n<li>Ibiza<\/li>\n<li>M\u00e1s<\/li>\n<\/ul>\n<p><\/div><div class=\"separator  transparent\" style=\"margin-top: 40px;margin-bottom: 0px;height: 0px;\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div   data-q_id=\"#features\"    class=\"vc_row wpb_row section vc_row-fluid  vc_custom_1455202688560 grid_section\" style='background-color:#f5f5f5; text-align:left;'><div class=\"section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class='q_icon_with_title tiny normal_icon'><div class=\"icon_holder\" style=\" \"><span data-icon-type=\"normal\"  data-icon-hover-color=\"#1abc9c\" style=\"font-size: 60px;\" class=\"qode_iwt_icon_holder q_font_awsome_icon fa-lg\"><i class=\"qodef-icon-linea-icon icon-basic-cloud qode_iwt_icon_element\" style=\"color: #b7b7b7;\" ><\/i><\/span><\/div><div class=\"icon_text_holder\" style=\"padding-left:70px;\"><div class=\"icon_text_inner\" style=\"\"><h4 class=\"icon_title\" style=\"\">Festa di addio al nubilato<\/h4><p style=''>Abbiamo l'esperienza di organizzare migliaia e migliaia di addii, dando alla sposa il miglior addio possibile, il tutto senza la tensione di trovare i migliori hotel e le migliori cose da fare, al miglior prezzo possibile.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class='q_icon_with_title tiny normal_icon'><div class=\"icon_holder\" style=\" \"><span data-icon-type=\"normal\"  data-icon-hover-color=\"#1abc9c\" style=\"font-size: 60px;\" class=\"qode_iwt_icon_holder q_font_awsome_icon fa-lg\"><i class=\"qodef-icon-linea-icon icon-basic-flag2 qode_iwt_icon_element\" style=\"color: #b7b7b7;\" ><\/i><\/span><\/div><div class=\"icon_text_holder\" style=\"padding-left:70px;\"><div class=\"icon_text_inner\" style=\"\"><h4 class=\"icon_title\" style=\"\">Addio al celibato<\/h4><p style=''>Abbiamo l'esperienza di organizzare migliaia e migliaia di addii, dando allo sposo il miglior addio possibile, il tutto senza la tensione di trovare i migliori hotel e le migliori cose da fare, al miglior prezzo possibile.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class='q_icon_with_title tiny normal_icon'><div class=\"icon_holder\" style=\" \"><span data-icon-type=\"normal\"  data-icon-hover-color=\"#1abc9c\" style=\"font-size: 60px;\" class=\"qode_iwt_icon_holder q_font_awsome_icon fa-lg\"><i class=\"qodef-icon-linea-icon icon-basic-chronometer qode_iwt_icon_element\" style=\"color: #b7b7b7;\" ><\/i><\/span><\/div><div class=\"icon_text_holder\" style=\"padding-left:70px;\"><div class=\"icon_text_inner\" style=\"\"><h4 class=\"icon_title\" style=\"\">Eventi<\/h4><p style=''>HEN PARTY NIGHT organizza e gestisce tutti i servizi per l'organizzazione di eventi, qualunque sia la vostra esigenza e il vostro budget, in pacchetti personalizzati. Abbiamo gestito centinaia di eventi, sia familiari che professionali e sociali. Mettiamo a vostra disposizione tutta questa enorme esperienza coordinando un team di aziende di primo livello che lavorano con spirito di collaborazione.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><section   data-q_id=\"#download\"    data-speed=\"1\" class=\"parallax_section_holder lazyload\" style = \" height:px; background-image:inherit;\" data-bg-image=\"url(&#039;https:\/\/henpartynight.com\/wp-content\/uploads\/2016\/02\/parallax2.jpg&#039;)\"><div class=\"parallax_content_full_width center\" ><div class='parallax_section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner vc_custom_1455031145900\"><div class=\"wpb_wrapper\"><div class=\"custom_font_holder\" style=\"font-family: Raleway; font-size: 126px; line-height: 126px; font-style: normal; font-weight: 700; color: #ffffff; text-decoration: none; letter-spacing: 0px; text-align: center;\">Contatto<\/div><div class=\"separator  transparent\" style=\"margin-top: 24px;margin-bottom: 0px;height: 0px;\"><\/div><div class='image_hover' style='' data-transition-delay=''><div class='images_holder'><a itemprop='url' href='https:\/\/henpartynight.com\/it\/contatto-addio-al-nubilato\/' target='_self'><img itemprop='image' class='active_image lazyload' data-src='https:\/\/henpartynight.com\/wp-content\/uploads\/2016\/02\/contacto-e1497858602971.png' alt='Main Image' src='data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==' style='--smush-placeholder-width: 451px; --smush-placeholder-aspect-ratio: 451\/200;' \/><img itemprop='image' class='hover_image lazyload' data-src='https:\/\/henpartynight.com\/wp-content\/uploads\/2016\/02\/contacto-e1497858602971.png' alt='Hover Image' src='data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==' style='--smush-placeholder-width: 451px; --smush-placeholder-aspect-ratio: 451\/200;' \/><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n<\/div>","protected":false},"excerpt":{"rendered":"Bar Crawl Ibiza The Bar Crawl Ibiza have become an important pillar of the party scene. Take a 3-5 bar tour with a local guide. You will have a shot included in each bar and in some packs you even have the option of an...","protected":false},"author":6,"featured_media":0,"parent":8144,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":{"footnotes":""},"class_list":["post-8166","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.8 - aioseo.com -->\n\t<meta name=\"description\" content=\"BAR CRAWL IBIZA SPECIALISTS! We make your Ibiza Pub Crawl unique and original! Meet people from all over the World! BAR CRAWL PARTY - Ibiza Pub Crawl Party\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"z76eTPFjdJeqIyJrFwxieY7obNIlRzKqIWxELIWL2lU\" \/>\n\t<meta name=\"keywords\" content=\"boat party,boatparty,boat parties,boatparties,boat party specialists\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/henpartynight.com\/it\/bar-crawl-2\/ibiza\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.8\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/henpartynight.com\\\/it\\\/bar-crawl-2\\\/ibiza\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/henpartynight.com\\\/it#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/henpartynight.com\\\/it\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/henpartynight.com\\\/it\\\/bar-crawl-2\\\/#listItem\",\"name\":\"Bar Crawl\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/henpartynight.com\\\/it\\\/bar-crawl-2\\\/#listItem\",\"position\":2,\"name\":\"Bar Crawl\",\"item\":\"https:\\\/\\\/henpartynight.com\\\/it\\\/bar-crawl-2\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/henpartynight.com\\\/it\\\/bar-crawl-2\\\/ibiza\\\/#listItem\",\"name\":\"Ibiza\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/henpartynight.com\\\/it#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/henpartynight.com\\\/it\\\/bar-crawl-2\\\/ibiza\\\/#listItem\",\"position\":3,\"name\":\"Ibiza\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/henpartynight.com\\\/it\\\/bar-crawl-2\\\/#listItem\",\"name\":\"Bar Crawl\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/henpartynight.com\\\/it\\\/#organization\",\"name\":\"Hen Party Night\",\"description\":\"Hen party Night, the best service\",\"url\":\"https:\\\/\\\/henpartynight.com\\\/it\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/henpartynight.com\\\/it\\\/bar-crawl-2\\\/ibiza\\\/#webpage\",\"url\":\"https:\\\/\\\/henpartynight.com\\\/it\\\/bar-crawl-2\\\/ibiza\\\/\",\"name\":\"Bar Crawl Ibiza - Pub Crawl Ibiza - Bar Tour Party Ibiza\",\"description\":\"BAR CRAWL IBIZA SPECIALISTS! We make your Ibiza Pub Crawl unique and original! Meet people from all over the World! BAR CRAWL PARTY - Ibiza Pub Crawl Party\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/henpartynight.com\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/henpartynight.com\\\/it\\\/bar-crawl-2\\\/ibiza\\\/#breadcrumblist\"},\"datePublished\":\"2022-09-21T13:29:01+00:00\",\"dateModified\":\"2024-04-16T09:13:51+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/henpartynight.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/henpartynight.com\\\/it\\\/\",\"name\":\"Hen Party Night\",\"description\":\"Hen party Night, the best service\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/henpartynight.com\\\/it\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Bar Crawl Ibiza - Pub Crawl Ibiza - Bar Tour Party Ibiza","description":"BAR CRAWL IBIZA SPECIALISTS! We make your Ibiza Pub Crawl unique and original! Meet people from all over the World! BAR CRAWL PARTY - Ibiza Pub Crawl Party","canonical_url":"https:\/\/henpartynight.com\/it\/bar-crawl-2\/ibiza\/","robots":"max-image-preview:large","keywords":"boat party,boatparty,boat parties,boatparties,boat party specialists","webmasterTools":{"google-site-verification":"z76eTPFjdJeqIyJrFwxieY7obNIlRzKqIWxELIWL2lU","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/henpartynight.com\/it\/bar-crawl-2\/ibiza\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/henpartynight.com\/it#listItem","position":1,"name":"Inicio","item":"https:\/\/henpartynight.com\/it","nextItem":{"@type":"ListItem","@id":"https:\/\/henpartynight.com\/it\/bar-crawl-2\/#listItem","name":"Bar Crawl"}},{"@type":"ListItem","@id":"https:\/\/henpartynight.com\/it\/bar-crawl-2\/#listItem","position":2,"name":"Bar Crawl","item":"https:\/\/henpartynight.com\/it\/bar-crawl-2\/","nextItem":{"@type":"ListItem","@id":"https:\/\/henpartynight.com\/it\/bar-crawl-2\/ibiza\/#listItem","name":"Ibiza"},"previousItem":{"@type":"ListItem","@id":"https:\/\/henpartynight.com\/it#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/henpartynight.com\/it\/bar-crawl-2\/ibiza\/#listItem","position":3,"name":"Ibiza","previousItem":{"@type":"ListItem","@id":"https:\/\/henpartynight.com\/it\/bar-crawl-2\/#listItem","name":"Bar Crawl"}}]},{"@type":"Organization","@id":"https:\/\/henpartynight.com\/it\/#organization","name":"Hen Party Night","description":"Hen party Night, the best service","url":"https:\/\/henpartynight.com\/it\/"},{"@type":"WebPage","@id":"https:\/\/henpartynight.com\/it\/bar-crawl-2\/ibiza\/#webpage","url":"https:\/\/henpartynight.com\/it\/bar-crawl-2\/ibiza\/","name":"Bar Crawl Ibiza - Pub Crawl Ibiza - Bar Tour Party Ibiza","description":"BAR CRAWL IBIZA SPECIALISTS! We make your Ibiza Pub Crawl unique and original! Meet people from all over the World! BAR CRAWL PARTY - Ibiza Pub Crawl Party","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/henpartynight.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/henpartynight.com\/it\/bar-crawl-2\/ibiza\/#breadcrumblist"},"datePublished":"2022-09-21T13:29:01+00:00","dateModified":"2024-04-16T09:13:51+00:00"},{"@type":"WebSite","@id":"https:\/\/henpartynight.com\/it\/#website","url":"https:\/\/henpartynight.com\/it\/","name":"Hen Party Night","description":"Hen party Night, the best service","inLanguage":"it-IT","publisher":{"@id":"https:\/\/henpartynight.com\/it\/#organization"}}]}},"aioseo_meta_data":{"post_id":"8166","title":"Bar Crawl Ibiza - Pub Crawl Ibiza - Bar Tour Party Ibiza","description":"BAR CRAWL IBIZA SPECIALISTS! We make your Ibiza Pub Crawl unique and original! Meet people from all over the World! BAR CRAWL PARTY - Ibiza Pub Crawl Party","keywords":[{"label":"Boat Party","value":"Boat Party"},{"label":"BoatParty","value":"BoatParty"},{"label":"Boat Parties","value":"Boat Parties"},{"label":"Boatparties","value":"Boatparties"},{"label":"Boat Party specialists","value":"Boat Party specialists"}],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":{"id":"#aioseo-web-page-65a912f2b3458","slug":"web-page","graphName":"WebPage","label":"P\u00e1gina web","properties":{"type":"WebPage","name":"","description":""}}},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-09-21 13:22:16","updated":"2025-10-14 15:53:43","seo_analyzer_scan_date":null},"_links":{"self":[{"href":"https:\/\/henpartynight.com\/it\/wp-json\/wp\/v2\/pages\/8166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/henpartynight.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/henpartynight.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/henpartynight.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/henpartynight.com\/it\/wp-json\/wp\/v2\/comments?post=8166"}],"version-history":[{"count":5,"href":"https:\/\/henpartynight.com\/it\/wp-json\/wp\/v2\/pages\/8166\/revisions"}],"predecessor-version":[{"id":13169,"href":"https:\/\/henpartynight.com\/it\/wp-json\/wp\/v2\/pages\/8166\/revisions\/13169"}],"up":[{"embeddable":true,"href":"https:\/\/henpartynight.com\/it\/wp-json\/wp\/v2\/pages\/8144"}],"wp:attachment":[{"href":"https:\/\/henpartynight.com\/it\/wp-json\/wp\/v2\/media?parent=8166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}